{"id":3414,"date":"2026-05-12T14:15:47","date_gmt":"2026-05-12T22:15:47","guid":{"rendered":"https:\/\/bettstruckparts.com\/?page_id=3414"},"modified":"2026-05-12T14:15:47","modified_gmt":"2026-05-12T22:15:47","slug":"bit-inspection-santa-fe-springs-ca","status":"publish","type":"page","link":"https:\/\/bettstruckparts.com\/es\/bit-inspection-santa-fe-springs-ca\/","title":{"rendered":"BIT Inspection Santa Fe Springs"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1761083000098\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center;\">BIT Inspections in Santa Fe Springs CA<\/h1>\n<h2 style=\"text-align: center;\"><span style=\"color: #ad1818;\">To schedule a BIT Inspection or speak with our service manager, call <a href=\"tel:562-941-2300\">(562) 941-2300<\/a><\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"ubtn-ctn-center\"><a class=\"ubtn-link ult-adjust-bottom-margin ubtn-center ubtn-normal\" href=\"tel:562-941-2300\" ><button type=\"button\" id=\"ubtn-9892\"  class=\"ubtn ult-adjust-bottom-margin ult-responsive ubtn-normal ubtn-fade-bg  none  ubtn-center   tooltip-6a97e5f983a63\"  data-hover=\"#FFFFFF\" data-border-color=\"#AD172B\" data-bg=\"#FFFFFF00\" data-hover-bg=\"#AD172B\" data-border-hover=\"#FFFFFF\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\"  data-ultimate-target='#ubtn-9892'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;border-radius:15px;border-width:3px;border-color:#AD172B;border-style:solid;background: #FFFFFF00;color: #AD172B;\"><span class=\"ubtn-hover\" style=\"background-color:#AD172B\"><\/span><span class=\"ubtn-data ubtn-text\" >Call for Santa Fe Springs BIT Inspection Appointments<\/span><\/button><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1744572361037\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: left;\"><strong>Betts Truck Parts &amp; Service in Santa Fe Springs, CA<\/strong> is your trusted partner for ensuring compliance with California&#8217;s stringent BIT (Biennial Inspection of Terminals) program.<\/p>\n<p style=\"text-align: left;\">With over two decades of experience and a commitment to exceptional customer service, we provide comprehensive BIT inspections that help you keep your trucks on the road and your business running smoothly.<\/p>\n<p style=\"text-align: left;\"><strong>Schedule your BIT Inspection in Santa Fe Springs today by calling us at (562) 941-2300<\/strong>\u00a0and speaking with our knowledgeable service manager.<\/p>\n<p style=\"text-align: left;\">At Betts Truck Parts &amp; Service Santa Fe Springs, we understand the importance of timely and accurate BIT inspections. We know that compliance is not just a legal requirement, but also a critical factor in maintaining the safety of your drivers and the integrity of your equipment.<\/p>\n<p style=\"text-align: left;\">That&#8217;s why we offer convenient BIT Inspection Services right at our location in Santa Fe Springs minimizing downtime and maximizing efficiency.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfPor qu\u00e9 elegir Betts Truck Parts &amp; Service para sus necesidades de inspecci\u00f3n BIT?<\/strong><\/h3>\n<ul>\n<li><strong>Especialistas experimentados en inspecci\u00f3n BIT:<\/strong> Nuestros inspectores certificados tienen una amplia experiencia en la realizaci\u00f3n de inspecciones BIT exhaustivas para una amplia gama de veh\u00edculos comerciales.<\/li>\n<li><strong>Comodidad m\u00f3vil:<\/strong> Did you know we can bring BIT inspections to your fleet? We bring the inspection to you, saving you valuable time and resources. Our mobile service eliminates the need to transport your vehicles to a fixed location, minimizing downtime and maximizing productivity.<\/li>\n<li><strong>Inspecciones exhaustivas:<\/strong> Realizamos inspecciones BIT exhaustivas que cubren todas las \u00e1reas requeridas, garantizando el cumplimiento de la normativa de California. Nuestras inspecciones incluyen controles de:\n<ul>\n<li><strong>Sistemas de frenado<\/strong><\/li>\n<li><strong>Sistemas de direcci\u00f3n<\/strong><\/li>\n<li><strong>Sistemas de suspensi\u00f3n<\/strong><\/li>\n<li><strong>Neum\u00e1ticos y ruedas<\/strong><\/li>\n<li><strong>Iluminaci\u00f3n y sistemas el\u00e9ctricos<\/strong><\/li>\n<li><strong>Bastidor y carrocer\u00eda<\/strong><\/li>\n<li><strong>Sujeci\u00f3n de la carga<\/strong><\/li>\n<li><strong>Documentaci\u00f3n y registro<br \/>\n<\/strong><\/li>\n<\/ul>\n<\/li>\n<li><strong>Servicio r\u00e1pido y eficaz<\/strong>: Comprendemos la importancia de que sus veh\u00edculos vuelvan r\u00e1pidamente a la carretera. Nuestros experimentados inspectores trabajan de manera eficiente para completar su inspecci\u00f3n BIT de manera oportuna, minimizando la interrupci\u00f3n de sus operaciones.<\/li>\n<li><strong>Excelente servicio de atenci\u00f3n al cliente:<\/strong> Nos comprometemos a ofrecer un servicio al cliente excepcional y a superar sus expectativas. Nuestro equipo est\u00e1 siempre disponible para responder a sus preguntas y resolver sus dudas.<\/li>\n<li><strong>Reputaci\u00f3n premiada<\/strong>: Betts Truck Parts &amp; Service was recently nominated by Truck Parts &amp; Service Magazine as a finalist for &#8220;Distributor of the Year 2020&#8221; for our commitment to our customers. This recognition is a testament to our dedication to providing quality service and building strong relationships with our clients. We are Betts Truck Parts Santa Fe Springs, a name you can rely on.<\/li>\n<\/ul>\n<p>We have been providing quality BIT inspections and truck services for the Los Angeles area since 1983!<\/p>\n<h3><strong>Comprender el programa BIT: Garantizar la seguridad y el cumplimiento<\/strong><\/h3>\n<p>The Biennial Inspection of Terminals (BIT) program is a comprehensive safety program mandated by the California Department of Motor Vehicles (DMV) to ensure the safe operation of commercial vehicles on California&#8217;s roadways.<\/p>\n<p>The program requires all motor carriers operating commercial vehicles with a gross vehicle weight rating (GVWR) of 10,001 pounds or more to undergo periodic inspections of their terminals and vehicles.<\/p>\n<h3><strong>Objetivos clave del Programa BIT:<\/strong><\/h3>\n<ul>\n<li>Reducir los accidentes de veh\u00edculos comerciales.<\/li>\n<li>Mejorar la seguridad de las operaciones de los veh\u00edculos comerciales.<\/li>\n<li>Garantizar el cumplimiento de la normativa estatal y federal.<\/li>\n<li>Promover una gesti\u00f3n responsable de los transportistas.<\/li>\n<\/ul>\n<h3><strong>\u00bfQu\u00e9 implica una inspecci\u00f3n BIT?<\/strong><\/h3>\n<p>Una inspecci\u00f3n BIT es una evaluaci\u00f3n exhaustiva de las pr\u00e1cticas de seguridad de un transportista y del estado de sus veh\u00edculos comerciales. La inspecci\u00f3n suele incluir una revisi\u00f3n de:<\/p>\n<ul>\n<li>Cualificaciones del conductor y registros de formaci\u00f3n.<\/li>\n<li>Registros de mantenimiento del veh\u00edculo.<\/li>\n<li>Historial de accidentes.<\/li>\n<li>Cumplimiento de la normativa sobre horas de servicio.<\/li>\n<li>Estado del veh\u00edculo, incluidos los sistemas de frenos, direcci\u00f3n, suspensi\u00f3n, neum\u00e1ticos e iluminaci\u00f3n.<\/li>\n<\/ul>\n<h3><strong>Preguntas comunes sobre las inspecciones BIT:<\/strong><\/h3>\n<ul>\n<li><strong>\u00bfCon qu\u00e9 frecuencia son necesarias las inspecciones de la BIT?<\/strong> Las inspecciones de la BIT son obligatorias al menos una vez cada dos a\u00f1os.<\/li>\n<li><strong>\u00bfQui\u00e9n es responsable de garantizar el cumplimiento de los TBI?<\/strong> El transportista es responsable de garantizar el cumplimiento del programa BIT.<\/li>\n<li><strong>\u00bfCu\u00e1les son las consecuencias del incumplimiento?<\/strong> El incumplimiento del programa BIT puede acarrear multas, sanciones e incluso la suspensi\u00f3n de la autorizaci\u00f3n para operar.<\/li>\n<\/ul>\n<p><strong>Contact Us Today for Your BIT Inspection in Santa Fe Springs!<\/strong><\/p>\n<p>Ensure your compliance with California&#8217;s BIT program and protect your business by scheduling a Mobile BIT Inspection with Betts Truck Parts &amp; Service in Santa Fe Springs. <a href=\"tel:Call us today at (562) 941-2300\">Call us today at (562) 941-2300<\/a>\u00a0para programar su inspecci\u00f3n y obtener m\u00e1s informaci\u00f3n sobre nuestros servicios.<\/p>\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-2268 alignleft\" src=\"https:\/\/bettstruckparts.com\/wp-content\/uploads\/2020\/09\/MG_2483-as-Smart-Object-1-300x200.png\" alt=\"Betts Truck Parts Santa Fe Springs CA\" width=\"300\" height=\"200\" srcset=\"https:\/\/bettstruckparts.com\/wp-content\/uploads\/2020\/09\/MG_2483-as-Smart-Object-1-300x200.png 300w, https:\/\/bettstruckparts.com\/wp-content\/uploads\/2020\/09\/MG_2483-as-Smart-Object-1-768x512.png 768w, https:\/\/bettstruckparts.com\/wp-content\/uploads\/2020\/09\/MG_2483-as-Smart-Object-1.png 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Betts Truck Parts &amp; Service Santa Fe Springs<\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\">\n<p><span itemprop=\"streetAddress\"><strong>9315 Santa Fe Springs Road<\/strong><\/span><br>\n<strong><span itemprop=\"addressLocality\">Santa Fe Springs<\/span>,\u00a0<span itemprop=\"addressRegion\">CA<\/span>\u00a0<span itemprop=\"postalCode\">90670<\/span><\/strong><br>\n<span itemprop=\"telephone\"><strong>Tel\u00e9fono<\/strong>:\u00a0562.941.2300<\/span><br>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Horario:<\/strong><br \/>\n<a href=\"https:\/\/bettstruckparts.com\/es\/lugares\/santa-fe-springs\/\">Check our working hours at Betts TPS Santa Fe Springs<\/a><\/p>\n<p>Need more information about BIT Inspections? See below to learn more about BIT Inspection requirements, what inspections are done for BIT Inspections, and frequently asked questions about BIT Inspections.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><em>&#8220;Great experience, first time and they had what I needed. They guys are cool and friendly.&#8221;<br \/>\n<\/em>&#8211; <em><strong>Frank H., Santa Fe Springs<\/strong><\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><em>&#8220;Great service &amp; Great people to work with. Always willing to help out with any sort of issues from start to end.&#8221;<br \/>\n<\/em>&#8211;\u00a0<em><strong>Jesus L., Santa Fe Springs<\/strong><\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper\"><img decoding=\"async\" width=\"978\" height=\"602\" src=\"https:\/\/bettstruckparts.com\/wp-content\/uploads\/2026\/05\/Santa-Fe-Springs-Map.png\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"Santa Fe Springs Map\" srcset=\"https:\/\/bettstruckparts.com\/wp-content\/uploads\/2026\/05\/Santa-Fe-Springs-Map.png 978w, https:\/\/bettstruckparts.com\/wp-content\/uploads\/2026\/05\/Santa-Fe-Springs-Map-300x185.png 300w, https:\/\/bettstruckparts.com\/wp-content\/uploads\/2026\/05\/Santa-Fe-Springs-Map-768x473.png 768w, https:\/\/bettstruckparts.com\/wp-content\/uploads\/2026\/05\/Santa-Fe-Springs-Map-18x12.png 18w\" sizes=\"(max-width: 978px) 100vw, 978px\"  data-dt-location=\"https:\/\/bettstruckparts.com\/es\/bit-inspection-santa-fe-springs-ca\/santa-fe-springs-map\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>C\u00f3mo llegar<\/strong><\/p>\n<p><a href=\"https:\/\/www.google.com\/maps\/place\/9315+Santa+Fe+Springs+Rd,+Santa+Fe+Springs,+CA+90670\/@33.9563666,-118.0552016,449m\/data=!3m1!1e3!4m6!3m5!1s0x80c2d3a8ad5abe6f:0x29e730670eba4544!8m2!3d33.9555968!4d-118.0547429!16s%2Fg%2F11bw4b8616?entry=ttu&amp;g_ep=EgoyMDI2MDUwNi4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">Betts Truck Parts &amp; Service, Santa Fe Springs<\/a> se encuentra en Santa Fe Springs Rd,\u00a0<a href=\"https:\/\/goo.gl\/maps\/8Hdp5DFtF3rKzKyV8\" target=\"_blank\" rel=\"noopener\">Santa Fe Springs<\/a>CA 90670. En\u00a0<a href=\"https:\/\/goo.gl\/maps\/fbWGYGDjFfFviSWX8\" target=\"_blank\" rel=\"noopener\">Aeropuerto de Long Beach (LGB)<\/a>\u00a0dir\u00edjase al este por Donald Douglas Dr hacia N Lakewood Blvd y gire a la derecha en N Lakewood Blvd. A continuaci\u00f3n, tome la rampa de la I-405 S y mant\u00e9ngase a la izquierda en la bifurcaci\u00f3n para continuar por la salida 26, siga las se\u00f1ales hacia Bellflower Blvd e incorp\u00f3rese a la I-405 S. En este punto, incorp\u00f3rese a la I-405 S y utilice los 2 carriles de la derecha para tomar la salida 24A hacia la I-605 N. A continuaci\u00f3n, contin\u00fae por la I-605 N y tome la salida 12 hacia Telegraph Rd en direcci\u00f3n a Santa Fe Springs. A continuaci\u00f3n, mant\u00e9ngase a la derecha en la bifurcaci\u00f3n, siga las se\u00f1ales hacia Telegraph Rd E e incorp\u00f3rese a Telegraph Rd e incorp\u00f3rese a Telegraph Rd. Finalmente, gire a la izquierda en Santa Fe Springs Rd y Betts Truck Parts &amp; Service, Santa Fe Springs estar\u00e1 a la izquierda.<\/p>\n<p>For additional questions, you can call us at (562) 941-2300.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #a11b1b;\">Santa Fe Springs, CA BIT Inspection FAQ&#8217;s<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div  class=\"vc_do_toggle vc_toggle vc_toggle_default   vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>\u00bfPor qu\u00e9 elegir Betts Truck Parts para las inspecciones BIT?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Betts Truck Parts se ha centrado en proporcionar una experiencia de cliente de \u00e9lite. Recientemente hemos sido finalistas en Truck Parts &amp; Service Magazine -una publicaci\u00f3n nacional del sector- como <strong>Finalista<\/strong> para <strong>Distribuidor del A\u00f1o 2020<\/strong>.<\/p>\n<p>We have over 30 years\u2019 experience, and provide fast, efficient commercial truck inspection services in Fresno to keep you in compliance and on the road.<\/p>\n<p>Tenemos 6 ubicaciones adicionales en California, Oreg\u00f3n y Arizona para servir a su flota.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_default   vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>Where in Santa Fe Springs do you perform BIT Inspections<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Betts Truck Parts &amp; Service Santa Fe Springs is located at 9315 Santa Fe Springs Road.<\/p>\n<p>Call our service manager in Santa Fe Springs at 562.941.2300 to confirm your BIT Inspection service area.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_default   vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>\u00bfSon bienales las inspecciones BIT de California?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>La legislaci\u00f3n californiana de principios de 2016 modific\u00f3 la anterior normativa de \"Inspecci\u00f3n bienal de terminales\".<\/p>\n<p>Tras este cambio, las inspecciones ya no son bienales. CHP puede inspeccionar una terminal cuando lo desee.<\/p>\n<p>Las terminales que reciban una calificaci\u00f3n \"satisfactoria\" s\u00f3lo podr\u00e1n ser inspeccionadas cada varios a\u00f1os. Las terminales que reciban una calificaci\u00f3n \"insatisfactoria\" volver\u00e1n a ser inspeccionadas por CHP en un plazo de 120 d\u00edas.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_default   vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>\u00bfD\u00f3nde puedo encontrar informaci\u00f3n oficial sobre las inspecciones del BIT?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Puede leer o descargar el documento oficial CHP \"Inspecci\u00f3n B\u00e1sica de Terminales (BIT)\" Informaci\u00f3n sobre el programa <a title=\"Programa de inspecci\u00f3n CHP BIT\" href=\"https:\/\/www.chp.ca.gov\/CommercialVehicleSectionSite\/Documents\/O%20chp800h.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a>.<\/p>\n<p>El proyecto de ley 529 de la Asamblea <a title=\"Proyecto de ley n\u00ba 529 de la Asamblea Legislaci\u00f3n sobre inspecci\u00f3n de la BIT\" href=\"http:\/\/leginfo.legislature.ca.gov\/faces\/billNavClient.xhtml?bill_id=201320140AB529\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a>.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_default   vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>\u00bfC\u00f3mo me ayudar\u00e1n las Betts Truck Parts a seguir cumpliendo la normativa?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Le proporcionamos los informes necesarios para cumplir la normativa, que incluyen informaci\u00f3n de mantenimiento que satisface los requisitos de una inspecci\u00f3n BIT. Nuestro software nos recordar\u00e1 cu\u00e1ndo sus veh\u00edculos deben someterse a una inspecci\u00f3n BIT para que usted siga cumpliendo la normativa.<\/p>\n<p>If you would like to speak directly with our service manager in Santa Fe Springs about BIT Inspections call our Santa Fe Springs branch at 562.941.2300.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_default   vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>\u00bfQu\u00e9 veh\u00edculos deben inspeccionarse cada 90 d\u00edas?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Los veh\u00edculos con un peso bruto de 10.000 libras y 3 o m\u00e1s ejes, o un peso bruto superior a 26.000 libras, deben someterse a una inspecci\u00f3n BIT cada 90 d\u00edas. La inspecci\u00f3n BIT debe realizarla un centro de servicio autorizado.<\/p>\n<p>Aseg\u00farese de llevar un registro preciso y actualizado de los conductores y de los registros de mantenimiento de su veh\u00edculo.<\/p>\n<\/div><\/div><div class=\"ubtn-ctn-center\"><a class=\"ubtn-link ult-adjust-bottom-margin ubtn-center ubtn-normal\" href=\"tel:562-941-2300\" ><button type=\"button\" id=\"ubtn-5070\"  class=\"ubtn ult-adjust-bottom-margin ult-responsive ubtn-normal ubtn-fade-bg  none  ubtn-center   tooltip-6a97e5f984cca\"  data-hover=\"#FFFFFF\" data-border-color=\"#AD172B\" data-bg=\"#FFFFFF00\" data-hover-bg=\"#AD172B\" data-border-hover=\"#FFFFFF\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\"  data-ultimate-target='#ubtn-5070'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;border-radius:15px;border-width:3px;border-color:#AD172B;border-style:solid;background: #FFFFFF00;color: #AD172B;\"><span class=\"ubtn-hover\" style=\"background-color:#AD172B\"><\/span><span class=\"ubtn-data ubtn-text\" >Call for Santa Fe Springs BIT Inspection Appointments<\/span><\/button><\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>BIT Inspections in Santa Fe Springs CA To schedule a BIT Inspection or speak with our service manager, call (562) 941-2300 Call for Santa Fe Springs BIT Inspection Appointments Betts Truck Parts &amp; Service in Santa Fe Springs, CA is your trusted partner for ensuring compliance with California&#8217;s stringent BIT (Biennial Inspection of Terminals) program.&hellip;<\/p>","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-microsite.php","meta":{"footnotes":""},"class_list":["post-3414","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/bettstruckparts.com\/es\/wp-json\/wp\/v2\/pages\/3414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bettstruckparts.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bettstruckparts.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bettstruckparts.com\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/bettstruckparts.com\/es\/wp-json\/wp\/v2\/comments?post=3414"}],"version-history":[{"count":0,"href":"https:\/\/bettstruckparts.com\/es\/wp-json\/wp\/v2\/pages\/3414\/revisions"}],"wp:attachment":[{"href":"https:\/\/bettstruckparts.com\/es\/wp-json\/wp\/v2\/media?parent=3414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}